{"id":6446,"date":"2025-10-16T06:15:25","date_gmt":"2025-10-16T06:15:25","guid":{"rendered":"https:\/\/diamondmicron.com\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/"},"modified":"2025-12-24T02:54:28","modified_gmt":"2025-12-24T02:54:28","slug":"snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh","status":"publish","type":"product","link":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/","title":{"rendered":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)"},"content":{"rendered":"<p>Beschreibung:<br \/>SND860 S\u00e4geschliff-Diamant ist ein Hochleistungs-Synthetikdiamantkorn (\u2265 99,8 % Kohlenstoffgehalt) mit blockartiger Kristallstruktur. Es ist optimiert f\u00fcr hohe Z\u00e4higkeit (Vickersh\u00e4rte: 7.500\u20138.000 HV) und Schlagfestigkeit (h\u00e4lt pl\u00f6tzlichen Krafteinwirkungen von 15\u201320 N stand, ohne zu brechen). Seine mittlere bis hohe Transparenz (80\u201385 % Lichtdurchl\u00e4ssigkeit) erm\u00f6glicht eine einfache Qualit\u00e4tspr\u00fcfung, w\u00e4hrend seine au\u00dfergew\u00f6hnliche thermische Stabilit\u00e4t (bis zu 1.000 \u00b0C) Langlebigkeit auch bei Anwendungen mit hoher Reibung ohne Leistungsabfall gew\u00e4hrleistet. <\/p>\n<p>SND860 wurde f\u00fcr vielseitige Anwendungen entwickelt und eignet sich hervorragend f\u00fcr Werkzeuge, die sowohl Langlebigkeit als auch Anpassungsf\u00e4higkeit erfordern. Es reduziert den Werkzeugverschlei\u00df bei groben geologischen Probenahmen um 30 % und gew\u00e4hrleistet eine gleichbleibende Schneidleistung bei Materialien wie Sandstein, Kalkstein und mittelhartem Gestein. Im Gegensatz zu Spezialk\u00f6rnungen (z. B. SND890 f\u00fcr extreme Hitze) bietet SND860 eine kosteng\u00fcnstige L\u00f6sung \u2013 mit einer 20\u201325 % l\u00e4ngeren Werkzeugstandzeit im Vergleich zu Einstiegsk\u00f6rnungen (z. B. SND830) ohne den hohen Preis von Diamantk\u00f6rnungen h\u00f6herer Qualit\u00e4t.  <\/p>\n<p>Verf\u00fcgbare Korngr\u00f6\u00dfen:<br \/>\n18\/20, 20\/25, 25\/30, 30\/35, 35\/40, 40\/45, 45\/50, 50\/60, 60\/70, 70\/80 Mesh (Korngr\u00f6\u00dfenbereich: 0,250 mm \u2013 1,00 mm), mit einer Gr\u00f6\u00dfentoleranz von \u00b14 % des Nennwerts, um eine gleichm\u00e4\u00dfige Werkzeughaftung und konsistente Leistung \u00fcber alle Chargen hinweg zu gew\u00e4hrleisten.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>H\u00e4ufig gestellte Fragen:<\/h3>\n<p><strong>Frage 1: Wie schneidet SND860 bei der geologischen Erkundung ab?<\/strong><br \/>\nA1:<br \/>SND860 genie\u00dft aufgrund seiner blockartigen Kristallz\u00e4higkeit und ausgezeichneten Schlagfestigkeit hohes Ansehen in der geologischen Exploration. Es widersteht pl\u00f6tzlichen St\u00f6\u00dfen beim Bohren in unebene Gesteinsformationen (z. B. Sandstein mit Quarzeinschl\u00fcssen) ohne zu brechen und gew\u00e4hrleistet so eine gleichbleibende Kernprobenqualit\u00e4t (Probenintegrit\u00e4t \u2265 95 %). Seine thermische Stabilit\u00e4t verhindert zudem den Abbau des Bohrguts bei l\u00e4ngeren Bohrvorg\u00e4ngen (bis zu 4 Stunden) und reduziert somit die H\u00e4ufigkeit des Werkzeugwechsels an abgelegenen Explorationsstandorten.  <\/p>\n<p><strong>Frage 2: Kann SND860 unter Hochtemperaturbedingungen eingesetzt werden?<\/strong><br \/>\nA2:<br \/>Ja. SND860 beh\u00e4lt seine Struktur und Schneidleistung bis zu einer Temperatur von 1.000 \u00b0C \u2013 ideal f\u00fcr Anwendungen mit hoher Reibung, wie z. B. Bauarbeiten (z. B. Stahlbetonschneiden in hei\u00dfen Klimazonen) oder Bergbau (z. B. Untertage-Erzgewinnung bei Umgebungstemperaturen von 50\u201360 \u00b0C). Im Gegensatz zu K\u00f6rnungen niedrigerer Qualit\u00e4t verliert SND860 unter diesen extremen Bedingungen weder an Sch\u00e4rfe noch wird es weicher.  <\/p>\n<p><strong>Frage 3: Was macht den SND860 branchen\u00fcbergreifend so vielseitig?<\/strong><br \/>\nA3:<br \/>\nDie ausgewogenen Eigenschaften von SND860 (mittlere bis hohe Z\u00e4higkeit, blockartige Form und \u00b14 % Gr\u00f6\u00dfentoleranz) machen es vielseitig einsetzbar f\u00fcr verschiedene Werkzeuge und Materialien. Es treibt Metallmatrix-Trennscheiben zum Asphaltschneiden im Bauwesen an, wird in Kernbohrkronen f\u00fcr mittelharte Erze (z. B. Eisenerz) im Bergbau verwendet und ist Bestandteil von kunstharzgebundenen Werkzeugen f\u00fcr die pr\u00e4zise Probenentnahme in der Geologie. Seine Vielseitigkeit macht mehrere Spezialsorten \u00fcberfl\u00fcssig und vereinfacht so die Lagerhaltung.  <\/p>\n<p><strong>Frage 4: Ist SND860 mit verschiedenen Werkzeugklebesystemen kompatibel?<\/strong><br \/>\nA4:<br \/>\nAbsolut. SND860 haftet zuverl\u00e4ssig auf allen g\u00e4ngigen Bindemittelsystemen: Metallmatrix (f\u00fcr hochbelastbare Bergbauwerkzeuge), Harz (f\u00fcr pr\u00e4zise geologische Probenahmebohrkronen) und sogar Keramikbindung (f\u00fcr industrielle Hochtemperaturbearbeitung). Der geringe Verunreinigungsgehalt (\u2264 0,2 %) gew\u00e4hrleistet eine starke Haftung zwischen Schleifmittel und Bindemittel und verhindert ein Abl\u00f6sen bei hohen Drehzahlen (bis zu 3.000 U\/min).  <\/p>\n<hr>\n<h3><strong>SND860 vs. SND880 vs. SND890 S\u00e4gekorn-Diamantschleifer: Dreifachvergleich<\/strong><\/h3>\n<table>\n<thead>\n<tr>\n<th>Vergleich der Abmessungen<\/th>\n<th>SND860 Diamant-S\u00e4gekorn<\/th>\n<th>SND880 Diamant-S\u00e4gekorn<\/th>\n<th>SND890 Diamant-S\u00e4gekorn<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Kernkristallstruktur<\/td>\n<td>Blockartiges Kuboktaeder; optimiert f\u00fcr hohe Z\u00e4higkeit<\/td>\n<td>Vollst\u00e4ndiges Kuboktaeder mit geraden, gratfreien Kanten; pr\u00e4zise Formgebung<\/td>\n<td>Hochregelm\u00e4\u00dfiges Kuboktaeder; minimale innere Einschl\u00fcsse; ultrastabile Struktur<\/td>\n<\/tr>\n<tr>\n<td><strong>Wichtigste technische Daten<\/strong><\/td>\n<td>&#8211; Reinheit: \u2265 99,8 % Kohlenstoff &#8211; H\u00e4rte: 7.500\u20138.000 HV &#8211; W\u00e4rmebest\u00e4ndigkeit: Bis zu 1.000 \u00b0C &#8211; Ma\u00dftoleranz: \u00b1 4 % &#8211; Schlagfestigkeit: H\u00e4lt 15\u201320 N stand<\/td>\n<td>&#8211; Reinheit: \u226599,9 % Kohlenstoff &#8211; Oberfl\u00e4cheng\u00fcte (nach dem Schneiden): Ra \u22641,6 \u03bcm &#8211; W\u00e4rmebest\u00e4ndigkeit: Bis zu 900 \u00b0C &#8211; Ma\u00dftoleranz: \u00b13 % &#8211; W\u00e4rmereduktion: 20 % gegen\u00fcber unregelm\u00e4\u00dfigen K\u00f6rnungen<\/td>\n<td>&#8211; Reinheit: \u2265 99,9 % Kohlenstoff &#8211; H\u00e4rte: &gt; 90 HRC &#8211; W\u00e4rmebest\u00e4ndigkeit: Bis zu 1200 \u00b0C &#8211; Ma\u00dftoleranz: \u00b1 5 % &#8211; Druckfestigkeit: &gt; 20 GPa<\/td>\n<\/tr>\n<tr>\n<td>Korngr\u00f6\u00dfenbereich<\/td>\n<td>18\/20 \u2013 50\/60 Mesh (0,250 mm \u2013 1,00 mm)<\/td>\n<td>18\/20 \u2013 70\/80 Mesh (0,212 mm \u2013 1,00 mm)<\/td>\n<td>20\/25 \u2013 45\/50 Mesh (0,425 mm \u2013 1,00 mm)<\/td>\n<\/tr>\n<tr>\n<td>Leistungsst\u00e4rke<\/td>\n<td>Ausgewogenes Verh\u00e4ltnis von H\u00e4rte und Wirtschaftlichkeit: Reduziert Werkzeugausbr\u00fcche um 30 %; 20\u201325 % l\u00e4ngere Standzeit als Einsteigerk\u00f6rnungen<\/td>\n<p>Pr\u00e4zision und Laufruhe: Minimiert Materialverlust( <\/p>\n<td>&lt;0&gt;<\/td>\n<p>5 %); &lt;sorgt f\u00fcr gratfreie Schnitte; ideal f\u00fcr Feinarbeiten<\/p>\n<td>Extreme Haltbarkeit und Hitzebest\u00e4ndigkeit: 30\u201340 % l\u00e4ngere Werkzeugstandzeit; erh\u00e4lt die Effizienz auch bei hoher Reibung<\/td>\n<\/tr>\n<tr>\n<td>Prim\u00e4re Anwendungsszenarien<\/td>\n<td>Allgemeine anspruchsvolle Aufgaben: Geologische Probenahme (Sandstein\/Kalkstein), Bauwesen (Asphalt-\/Betonschneiden), Abbau mittelharter Erze (Eisenerz)<\/td>\n<td>Pr\u00e4zisionsaufgaben: Steinpolieren (Marmor\/Granit), Kernbohrungen f\u00fcr Keramikfliesen, Glaskantenbearbeitung, D\u00fcnnschliff-Probenahme<\/td>\n<td>Schwerbeanspruchte Aufgaben: Tiefbau (Erzgewinnung), Hartgesteinsbohrungen (Granit\/Basalt), Tunnelbau, Verarbeitung von feuerfesten Materialien<\/td>\n<\/tr>\n<tr>\n<td>Empfohlene Werkzeugtypen<\/td>\n<td>Metallmatrix-S\u00e4gebl\u00e4tter, Standard-Kernbohrer, Bergbaubohrer<\/td>\n<td>Harzgebundene S\u00e4gebl\u00e4tter, galvanisierte Kernbohrer, Feindrahts\u00e4gen<\/td>\n<td>Hochleistungs-Metallmatrix-S\u00e4gebl\u00e4tter, Industriekernbohrer, Diamantdr\u00e4hte mit hohem Drehmoment<\/td>\n<\/tr>\n<tr>\n<td>Geeignete Branchen<\/td>\n<td>Mittelbergbau, Bauwesen, geologische Erkundung (allgemein), Infrastruktur<\/td>\n<td>Steinverarbeitung, Keramikherstellung, Architekturglas, Laborgeologie<\/td>\n<td>Gro\u00dfbergbau\/Tiefbergbau, Erd\u00f6l- und Erdgasexploration, Hoch- und Tiefbau, Feuerfesttechnik<\/td>\n<\/tr>\n<tr>\n<td>Preis-Leistungs-Verh\u00e4ltnis<\/td>\n<td>Mittlere Preisklasse: Kosteng\u00fcnstig f\u00fcr den allgemeinen Einsatz in gro\u00dfen Mengen<\/td>\n<td>Mittlere bis Premiumklasse: Wertvoll f\u00fcr pr\u00e4zisionskritische Anwendungen<\/td>\n<td>Premiumklasse: Investition f\u00fcr extreme Belastbarkeit<\/td>\n<\/tr>\n<tr>\n<td>Wichtigster Kundennutzen<\/td>\n<td>\u201eEin Werkzeug f\u00fcr viele Aufgaben\u201c \u2013 vereinfacht die Lagerhaltung und vermeidet unn\u00f6tige Kosten<\/td>\n<td>\u201eGleichm\u00e4\u00dfige, konsistente Ergebnisse\u201c \u2013 reduziert Nacharbeiten und verbessert die Produktqualit\u00e4t<\/td>\n<td>\u201eWeniger Ausfallzeiten, mehr Produktivit\u00e4t\u201c \u2013 weniger Werkzeugwechsel, zuverl\u00e4ssig auch unter h\u00e4rtesten Bedingungen<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Verbinden mit:<\/p>\n<p><a href=\"https:\/\/diamondmicron.com\/de\/product\/snd890-premium-saegekorn-diamant-hohe-thermische-stabilitaet-fuer-professionelle-schneid-und-bohrwerkzeuge\/\">SND890 <\/a> <a href=\"https:\/\/diamondmicron.com\/de\/product\/snd880-praezisions-saegekorn-diamant-gerade-kristallkanten-fuer-glatte-schnitte-und-praezises-kernbohren-18-80-mesh\/\">SND880 <\/a> <a href=\"https:\/\/diamondmicron.com\/product\/saw-grit-snd840\/\">SND840<\/a> <a href=\"https:\/\/diamondmicron.com\/product\/saw-grit-snd830\/\">SND830<\/a> <a href=\"https:\/\/diamondmicron.com\/product\/saw-grit-snd820\/\"> SND820<\/a> <a href=\"https:\/\/diamondmicron.com\/product\/saw-grit-snd815\/\"> SND815<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie. <\/p>\n","protected":false},"featured_media":6450,"template":"","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_brand":[147,51],"product_cat":[6480],"product_tag":[6503,6500,6502,6501,6498,6499],"class_list":{"0":"post-6446","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-sinodiam-saw-grit-diamond","7":"product_brand-siondiam","8":"product_cat-diamantsage","9":"product_tag-chinesischer-lieferant-von-synthetischen-diamanten","10":"product_tag-diamant-mittlerer-harte","11":"product_tag-diamantstaub-fur-den-bau","12":"product_tag-geologische-erkundung-von-diamanten","13":"product_tag-granat-diamant-snd860","14":"product_tag-schlagfestes-diamantkorn","15":"desktop-align-left","16":"tablet-align-left","17":"mobile-align-left","19":"first","20":"instock","21":"shipping-taxable","22":"product-type-simple"},"aioseo_notices":[],"uagb_featured_image_src":{"full":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860.jpg",1135,1136,false],"thumbnail":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-150x150.jpg",150,150,true],"medium":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-300x300.jpg",300,300,true],"medium_large":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-768x769.jpg",768,769,true],"large":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860.jpg",1135,1136,false],"2048x2048":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860.jpg",1135,1136,false],"woocommerce_thumbnail":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-600x601.jpg",600,601,true],"woocommerce_gallery_thumbnail":["https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"SinoDiam Technical Team","author_link":"https:\/\/diamondmicron.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.","aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.8.3.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.8.3.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives - High-Quality Diamond Superabrasives for Global Applications\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives\" \/>\n\t\t<meta property=\"og:description\" content=\"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-10-16T06:15:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-24T02:54:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diamondmicron\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/geschaeft\\\/#listItem\",\"name\":\"Gesch\\u00e4ft\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/geschaeft\\\/#listItem\",\"position\":2,\"name\":\"Gesch\\u00e4ft\",\"item\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/geschaeft\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/marchio\\\/siondiam\\\/#listItem\",\"name\":\"SionDiam\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/marchio\\\/siondiam\\\/#listItem\",\"position\":3,\"name\":\"SionDiam\",\"item\":\"https:\\\/\\\/diamondmicron.com\\\/marchio\\\/siondiam\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/Marke\\\/siondiam\\\/sinodiam-saw-grit-diamond\\\/#listItem\",\"name\":\"SinoDiam Saw Grit Diamond\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/geschaeft\\\/#listItem\",\"name\":\"Gesch\\u00e4ft\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/Marke\\\/siondiam\\\/sinodiam-saw-grit-diamond\\\/#listItem\",\"position\":4,\"name\":\"SinoDiam Saw Grit Diamond\",\"item\":\"https:\\\/\\\/diamondmicron.com\\\/Marke\\\/siondiam\\\/sinodiam-saw-grit-diamond\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#listItem\",\"name\":\"SND860 Hartes S\\u00e4gekorn-Diamant \\u2013 Schlagfest f\\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/marchio\\\/siondiam\\\/#listItem\",\"name\":\"SionDiam\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#listItem\",\"position\":5,\"name\":\"SND860 Hartes S\\u00e4gekorn-Diamant \\u2013 Schlagfest f\\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/Marke\\\/siondiam\\\/sinodiam-saw-grit-diamond\\\/#listItem\",\"name\":\"SinoDiam Saw Grit Diamond\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#organization\",\"name\":\"Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives\",\"description\":\"High-Quality Diamond Superabrasives for Global Applications\",\"url\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamondmicron.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-LOGO-NEW-1.jpg\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#organizationLogo\",\"width\":1165,\"height\":388},\"image\":{\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sinodiam-diamond-powder\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#webpage\",\"url\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/\",\"name\":\"SND860 Hartes S\\u00e4gekorn-Diamant \\u2013 Schlagfest f\\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives\",\"description\":\"SND860 ist ein vielseitiges, mittel- bis hochhartes S\\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\\u00e4ltnis von Langlebigkeit, thermischer Stabilit\\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamondmicron.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SND860.jpg\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#mainImage\",\"width\":1135,\"height\":1136,\"caption\":\"SND860 S\\u00e4gekorn-Diamant \\u2013 Blockige Kristallstruktur f\\u00fcr schlagfeste geologische Werkzeuge\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/product\\\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\\\/#mainImage\"},\"datePublished\":\"2025-10-16T06:15:25+00:00\",\"dateModified\":\"2025-12-24T02:54:28+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/\",\"name\":\"Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives\",\"description\":\"High-Quality Diamond Superabrasives for Global Applications\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamondmicron.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives<\/title>\n\n","aioseo_head_json":{"title":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives","description":"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.","canonical_url":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/diamondmicron.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/geschaeft\/#listItem","name":"Gesch\u00e4ft"}},{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/geschaeft\/#listItem","position":2,"name":"Gesch\u00e4ft","item":"https:\/\/diamondmicron.com\/de\/geschaeft\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/marchio\/siondiam\/#listItem","name":"SionDiam"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/marchio\/siondiam\/#listItem","position":3,"name":"SionDiam","item":"https:\/\/diamondmicron.com\/marchio\/siondiam\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/#listItem","name":"SinoDiam Saw Grit Diamond"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/geschaeft\/#listItem","name":"Gesch\u00e4ft"}},{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/#listItem","position":4,"name":"SinoDiam Saw Grit Diamond","item":"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#listItem","name":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/marchio\/siondiam\/#listItem","name":"SionDiam"}},{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#listItem","position":5,"name":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/#listItem","name":"SinoDiam Saw Grit Diamond"}}]},{"@type":"Organization","@id":"https:\/\/diamondmicron.com\/de\/#organization","name":"Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives","description":"High-Quality Diamond Superabrasives for Global Applications","url":"https:\/\/diamondmicron.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#organizationLogo","width":1165,"height":388},"image":{"@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/company\/sinodiam-diamond-powder"]},{"@type":"WebPage","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#webpage","url":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/","name":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives","description":"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/diamondmicron.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/SND860.jpg","@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#mainImage","width":1135,"height":1136,"caption":"SND860 S\u00e4gekorn-Diamant \u2013 Blockige Kristallstruktur f\u00fcr schlagfeste geologische Werkzeuge"},"primaryImageOfPage":{"@id":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/#mainImage"},"datePublished":"2025-10-16T06:15:25+00:00","dateModified":"2025-12-24T02:54:28+00:00"},{"@type":"WebSite","@id":"https:\/\/diamondmicron.com\/de\/#website","url":"https:\/\/diamondmicron.com\/de\/","name":"Your Trusted Supplier of Synthetic Diamond Powder & Superabrasives","description":"High-Quality Diamond Superabrasives for Global Applications","inLanguage":"de-DE","publisher":{"@id":"https:\/\/diamondmicron.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives - High-Quality Diamond Superabrasives for Global Applications","og:type":"article","og:title":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives","og:description":"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.","og:url":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/","og:image":"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg","og:image:secure_url":"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg","article:published_time":"2025-10-16T06:15:25+00:00","article:modified_time":"2025-12-24T02:54:28+00:00","article:publisher":"https:\/\/www.facebook.com\/diamondmicron\/","twitter:card":"summary_large_image","twitter:title":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh) - Your Trusted Supplier of Synthetic Diamond Powder &amp; Superabrasives","twitter:description":"SND860 ist ein vielseitiges, mittel- bis hochhartes S\u00e4gekorn-Diamantkorn mit blockartiger Kristallform und hoher Schlagfestigkeit. Es bietet ein optimales Verh\u00e4ltnis von Langlebigkeit, thermischer Stabilit\u00e4t und Wirtschaftlichkeit und ist damit die erste Wahl f\u00fcr allgemeine Schneidwerkzeuge in Geologie, Bauwesen und Industrie.","twitter:image":"https:\/\/diamondmicron.com\/wp-content\/uploads\/2025\/10\/cropped-LOGO-NEW-1.jpg"},"aioseo_meta_data":[],"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/diamondmicron.com\/de\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/diamondmicron.com\/de\/geschaeft\/\" title=\"Gesch\u00e4ft\">Gesch\u00e4ft<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/diamondmicron.com\/marchio\/siondiam\/\" title=\"SionDiam\">SionDiam<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/\" title=\"SinoDiam Saw Grit Diamond\">SinoDiam Saw Grit Diamond<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tSND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/diamondmicron.com\/de\/"},{"label":"Gesch\u00e4ft","link":"https:\/\/diamondmicron.com\/de\/geschaeft\/"},{"label":"SionDiam","link":"https:\/\/diamondmicron.com\/marchio\/siondiam\/"},{"label":"SinoDiam Saw Grit Diamond","link":"https:\/\/diamondmicron.com\/Marke\/siondiam\/sinodiam-saw-grit-diamond\/"},{"label":"SND860 Hartes S\u00e4gekorn-Diamant \u2013 Schlagfest f\u00fcr geologische und Bauwerkzeuge (18-80 Mesh)","link":"https:\/\/diamondmicron.com\/de\/product\/snd860-hartes-saegekorn-diamant-schlagfest-fuer-geologische-und-bauwerkzeuge-18-80-mesh\/"}],"_links":{"self":[{"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/product\/6446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/media\/6450"}],"wp:attachment":[{"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/media?parent=6446"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/product_brand?post=6446"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/product_cat?post=6446"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/diamondmicron.com\/de\/wp-json\/wp\/v2\/product_tag?post=6446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}